{"id":1036,"date":"2018-10-17T14:57:37","date_gmt":"2018-10-17T17:57:37","guid":{"rendered":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/?p=1036"},"modified":"2018-10-18T12:37:02","modified_gmt":"2018-10-18T15:37:02","slug":"maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts","status":"publish","type":"post","link":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/","title":{"rendered":"Maioria dos brasileiros reconhece preconceito contra LGBTs"},"content":{"rendered":"<p>A pesquisa\u00a0<em>Diversidade Sexual e Homofobia no Brasil: Intoler\u00e2ncia e respeito \u00e0s diferen\u00e7as sexuais<\/em> realizada pela\u00a0<a href=\"http:\/\/novo.fpabramo.org.br\/\" target=\"_blank\" rel=\"noopener\">FPA (Funda\u00e7\u00e3o Perseu Abramo)<\/a>\u00a0em parceria com a\u00a0<a href=\"http:\/\/www.rls.org.br\/\" target=\"_blank\" rel=\"noopener\">RLS (Funda\u00e7\u00e3o Rosa Luxemburgo Stiftung)<\/a>\u00a0buscou \u201cinvestigar as percep\u00e7\u00f5es (indicadores subjetivos) sobre o fen\u00f4meno de pr\u00e1ticas sociais discriminat\u00f3rias em raz\u00e3o da orienta\u00e7\u00e3o sexual e da identidade de g\u00eanero das pessoas, bem como manifesta\u00e7\u00f5es diretas e indiretas de atitudes preconceituosas\u201d.<\/p>\n<p>Em seus resultados, a pesquisa mostra que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT. Entre gays, l\u00e9sbicas, bissexuais, travestis e transexuais, quase 100% reconhece que essa parcela da popula\u00e7\u00e3o sofre preconceito.<\/p>\n<p><script id=\"infogram_0_349f08ec-85fd-4262-892f-296243494161\" title=\"Exist\u00eancia de preconceito contra LGBT no Brasil \" src=\"https:\/\/e.infogram.com\/js\/dist\/embed.js?UAZ\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesquisa\u00a0Diversidade Sexual e Homofobia no Brasil: Intoler\u00e2ncia e respeito \u00e0s diferen\u00e7as sexuais realizada pela\u00a0FPA (Funda\u00e7\u00e3o Perseu Abramo)\u00a0em parceria com a\u00a0RLS (Funda\u00e7\u00e3o Rosa Luxemburgo Stiftung)\u00a0buscou \u201cinvestigar as percep\u00e7\u00f5es (indicadores subjetivos) sobre o fen\u00f4meno de pr\u00e1ticas sociais discriminat\u00f3rias em raz\u00e3o da orienta\u00e7\u00e3o sexual e da identidade de g\u00eanero das pessoas, bem como manifesta\u00e7\u00f5es diretas e indiretas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[149,147,121,148,60,151,138,150],"class_list":["post-1036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-violencia-contra-mulheres-lesbicas-bis-e-trans","tag-bissexuais","tag-gays","tag-homofobia","tag-lesbicas","tag-percepcao","tag-preconceito","tag-transexuais","tag-travestis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maioria dos brasileiros reconhece preconceito contra LGBTs<\/title>\n<meta name=\"description\" content=\"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maioria dos brasileiros reconhece preconceito contra LGBTs\" \/>\n<meta property=\"og:description\" content=\"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/\" \/>\n<meta property=\"og:site_name\" content=\"Viol\u00eancia contra a mulher em dados\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-17T17:57:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-18T15:37:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"353\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/#\\\/schema\\\/person\\\/3f4868ca6b9ee4f83c32176030375e30\"},\"headline\":\"Maioria dos brasileiros reconhece preconceito contra LGBTs\",\"datePublished\":\"2018-10-17T17:57:37+00:00\",\"dateModified\":\"2018-10-18T15:37:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/\"},\"wordCount\":122,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\\\/sites\\\/5\\\/2018\\\/10\\\/existenci-de-preconceito-destaque.jpg\",\"keywords\":[\"bissexuais\",\"gays\",\"homofobia\",\"l\u00e9sbicas\",\"percepcao\",\"preconceito\",\"transexuais\",\"travestis\"],\"articleSection\":[\"Viol\u00eancia contra mulheres l\u00e9sbicas, bis e trans\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/\",\"url\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/\",\"name\":\"Maioria dos brasileiros reconhece preconceito contra LGBTs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\\\/sites\\\/5\\\/2018\\\/10\\\/existenci-de-preconceito-destaque.jpg\",\"datePublished\":\"2018-10-17T17:57:37+00:00\",\"dateModified\":\"2018-10-18T15:37:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/#\\\/schema\\\/person\\\/3f4868ca6b9ee4f83c32176030375e30\"},\"description\":\"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\\\/sites\\\/5\\\/2018\\\/10\\\/existenci-de-preconceito-destaque.jpg\",\"contentUrl\":\"https:\\\/\\\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\\\/sites\\\/5\\\/2018\\\/10\\\/existenci-de-preconceito-destaque.jpg\",\"width\":353,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maioria dos brasileiros reconhece preconceito contra LGBTs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/#website\",\"url\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/\",\"name\":\"Viol\u00eancia contra a mulher em dados\",\"description\":\"&lt;strong&gt;Viol\u00eancia contra as Mulheres em Dados&lt;\\\/strong&gt; re\u00fane pesquisas e dados recentes relacionados \u00e0s viol\u00eancias contra as mulheres no Brasil, com base no monitoramento e curadoria realizados pelo Instituto Patr\u00edcia Galv\u00e3o \u2013 com foco na viol\u00eancia dom\u00e9stica, sexual e online, no feminic\u00eddio e na intersec\u00e7\u00e3o com o racismo e a LGBT+fobia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/#\\\/schema\\\/person\\\/3f4868ca6b9ee4f83c32176030375e30\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/dossies.agenciapatriciagalvao.org.br\\\/violencia-em-dados\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maioria dos brasileiros reconhece preconceito contra LGBTs","description":"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/","og_locale":"pt_BR","og_type":"article","og_title":"Maioria dos brasileiros reconhece preconceito contra LGBTs","og_description":"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT","og_url":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/","og_site_name":"Viol\u00eancia contra a mulher em dados","article_published_time":"2018-10-17T17:57:37+00:00","article_modified_time":"2018-10-18T15:37:02+00:00","og_image":[{"width":353,"height":240,"url":"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#article","isPartOf":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/"},"author":{"name":"admin","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/#\/schema\/person\/3f4868ca6b9ee4f83c32176030375e30"},"headline":"Maioria dos brasileiros reconhece preconceito contra LGBTs","datePublished":"2018-10-17T17:57:37+00:00","dateModified":"2018-10-18T15:37:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/"},"wordCount":122,"commentCount":0,"image":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#primaryimage"},"thumbnailUrl":"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg","keywords":["bissexuais","gays","homofobia","l\u00e9sbicas","percepcao","preconceito","transexuais","travestis"],"articleSection":["Viol\u00eancia contra mulheres l\u00e9sbicas, bis e trans"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/","url":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/","name":"Maioria dos brasileiros reconhece preconceito contra LGBTs","isPartOf":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#primaryimage"},"image":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#primaryimage"},"thumbnailUrl":"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg","datePublished":"2018-10-17T17:57:37+00:00","dateModified":"2018-10-18T15:37:02+00:00","author":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/#\/schema\/person\/3f4868ca6b9ee4f83c32176030375e30"},"description":"A pesquisa revelou que a maioria dos brasileiros e brasileiras entrevistados acredita que existe, sim, preconceito contra pessoas LGBT","breadcrumb":{"@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#primaryimage","url":"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg","contentUrl":"https:\/\/assets-dossies-ipg-v2.nyc3.digitaloceanspaces.com\/sites\/5\/2018\/10\/existenci-de-preconceito-destaque.jpg","width":353,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/maioria-dos-brasileiros-reconhece-preconceito-contra-lgbts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/"},{"@type":"ListItem","position":2,"name":"Maioria dos brasileiros reconhece preconceito contra LGBTs"}]},{"@type":"WebSite","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/#website","url":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/","name":"Viol\u00eancia contra a mulher em dados","description":"&lt;strong&gt;Viol\u00eancia contra as Mulheres em Dados&lt;\/strong&gt; re\u00fane pesquisas e dados recentes relacionados \u00e0s viol\u00eancias contra as mulheres no Brasil, com base no monitoramento e curadoria realizados pelo Instituto Patr\u00edcia Galv\u00e3o \u2013 com foco na viol\u00eancia dom\u00e9stica, sexual e online, no feminic\u00eddio e na intersec\u00e7\u00e3o com o racismo e a LGBT+fobia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/#\/schema\/person\/3f4868ca6b9ee4f83c32176030375e30","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1dca91a40b3dd364beafcaf9d5f369aadbf73fa3745cda6fb3ac9c69a5c796a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/author\/admin\/"}]}},"views":3157,"_links":{"self":[{"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/posts\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/comments?post=1036"}],"version-history":[{"count":1,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/posts\/1036\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/posts\/1036\/revisions\/1037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/media\/1038"}],"wp:attachment":[{"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/media?parent=1036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/categories?post=1036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dossies.agenciapatriciagalvao.org.br\/violencia-em-dados\/wp-json\/wp\/v2\/tags?post=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}